{"id":35089,"date":"2024-05-22T17:30:55","date_gmt":"2024-05-22T15:30:55","guid":{"rendered":"https:\/\/internacional.umh.es\/?p=35089"},"modified":"2024-05-22T17:54:45","modified_gmt":"2024-05-22T15:54:45","slug":"se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25","status":"publish","type":"post","link":"https:\/\/internacional.umh.es\/ca\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/","title":{"rendered":"<span lang=\"es\">(Espa\u00f1ol) Se publica la convocatoria de ayudas UMH para los participantes en el programa SICUE 24\/25<\/span>"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-ca\">Ho sent, per\u00f2 aquesta entrada nom\u00e9s est\u00e0 disponible en <a href=\"https:\/\/internacional.umh.es\/es\/wp-json\/wp\/v2\/posts\/35089\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Espa\u00f1ol\">Espanyol Europeu<\/a> i <a href=\"https:\/\/internacional.umh.es\/en\/wp-json\/wp\/v2\/posts\/35089\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">Angl\u00e8s Americ\u00e0<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ho sent, per\u00f2 aquesta entrada nom\u00e9s est\u00e0 disponible en Espanyol Europeu i Angl\u00e8s Americ\u00e0.<\/p>\n","protected":false},"author":6508,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_links_to":"","_links_to_target":""},"categories":[524],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internacional.umh.es\/ca\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(Espa\u00f1ol) Se publica la convocatoria de ayudas UMH para los participantes en el programa SICUE 24\/25 - Internacionalitzaci\u00f3 i Cooperaci\u00f3\" \/>\n<meta property=\"og:description\" content=\"Ho sent, per\u00f2 aquesta entrada nom\u00e9s est\u00e0 disponible en Espanyol Europeu i Angl\u00e8s Americ\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/\" \/>\n<meta property=\"og:site_name\" content=\"Internacionalitzaci\u00f3 i Cooperaci\u00f3\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-22T15:30:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-22T15:54:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internacional.umh.es\/files\/2024\/05\/Publicaciones-Instagram-1-300x300.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"l.sempere\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/internacional.umh.es\/en\/#website\",\"url\":\"https:\/\/internacional.umh.es\/en\/\",\"name\":\"Internacionalitzaci\\u00f3 i Cooperaci\\u00f3\",\"description\":\"Universitat Miguel Hern\\u00e1ndez d&#039;Elx\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/internacional.umh.es\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/#primaryimage\",\"inLanguage\":\"ca\",\"url\":\"https:\/\/internacional.umh.es\/files\/2024\/05\/Publicaciones-Instagram-1.png\",\"contentUrl\":\"https:\/\/internacional.umh.es\/files\/2024\/05\/Publicaciones-Instagram-1.png\",\"width\":1080,\"height\":1080},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/#webpage\",\"url\":\"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/\",\"name\":\"<span lang=\\\"es\\\">(Espa\\u00f1ol) Se publica la convocatoria de ayudas UMH para los participantes en el programa SICUE 24\/25 - Internacionalitzaci\\u00f3 i Cooperaci\\u00f3<\/span>\",\"isPartOf\":{\"@id\":\"https:\/\/internacional.umh.es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/#primaryimage\"},\"datePublished\":\"2024-05-22T15:30:55+00:00\",\"dateModified\":\"2024-05-22T15:54:45+00:00\",\"author\":{\"@id\":\"https:\/\/internacional.umh.es\/en\/#\/schema\/person\/fd81c4b213566f3add82d0f214928dfa\"},\"breadcrumb\":{\"@id\":\"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/internacional.umh.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se publica la convocatoria de ayudas UMH para los participantes en el programa SICUE 24\/25\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/internacional.umh.es\/en\/#\/schema\/person\/fd81c4b213566f3add82d0f214928dfa\",\"name\":\"l.sempere\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/internacional.umh.es\/en\/#personlogo\",\"inLanguage\":\"ca\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1f9861c855fb90ab758094a71cf6e565?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1f9861c855fb90ab758094a71cf6e565?s=96&d=mm&r=g\",\"caption\":\"l.sempere\"},\"url\":\"https:\/\/internacional.umh.es\/ca\/author\/l-sempere\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internacional.umh.es\/ca\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/","og_locale":"ca_ES","og_type":"article","og_title":"(Espa\u00f1ol) Se publica la convocatoria de ayudas UMH para los participantes en el programa SICUE 24\/25 - Internacionalitzaci\u00f3 i Cooperaci\u00f3","og_description":"Ho sent, per\u00f2 aquesta entrada nom\u00e9s est\u00e0 disponible en Espanyol Europeu i Angl\u00e8s Americ\u00e0.","og_url":"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/","og_site_name":"Internacionalitzaci\u00f3 i Cooperaci\u00f3","article_published_time":"2024-05-22T15:30:55+00:00","article_modified_time":"2024-05-22T15:54:45+00:00","og_image":[{"url":"https:\/\/internacional.umh.es\/files\/2024\/05\/Publicaciones-Instagram-1-300x300.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"l.sempere"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/internacional.umh.es\/en\/#website","url":"https:\/\/internacional.umh.es\/en\/","name":"Internacionalitzaci\u00f3 i Cooperaci\u00f3","description":"Universitat Miguel Hern\u00e1ndez d&#039;Elx","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internacional.umh.es\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"},{"@type":"ImageObject","@id":"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/#primaryimage","inLanguage":"ca","url":"https:\/\/internacional.umh.es\/files\/2024\/05\/Publicaciones-Instagram-1.png","contentUrl":"https:\/\/internacional.umh.es\/files\/2024\/05\/Publicaciones-Instagram-1.png","width":1080,"height":1080},{"@type":"WebPage","@id":"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/#webpage","url":"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/","name":"<span lang=\"es\">(Espa\u00f1ol) Se publica la convocatoria de ayudas UMH para los participantes en el programa SICUE 24\/25 - Internacionalitzaci\u00f3 i Cooperaci\u00f3<\/span>","isPartOf":{"@id":"https:\/\/internacional.umh.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/#primaryimage"},"datePublished":"2024-05-22T15:30:55+00:00","dateModified":"2024-05-22T15:54:45+00:00","author":{"@id":"https:\/\/internacional.umh.es\/en\/#\/schema\/person\/fd81c4b213566f3add82d0f214928dfa"},"breadcrumb":{"@id":"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/internacional.umh.es\/2024\/05\/22\/se-publica-la-convocatoria-de-ayudas-umh-para-los-participantes-en-el-programa-sicue-24-25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/internacional.umh.es\/"},{"@type":"ListItem","position":2,"name":"Se publica la convocatoria de ayudas UMH para los participantes en el programa SICUE 24\/25"}]},{"@type":"Person","@id":"https:\/\/internacional.umh.es\/en\/#\/schema\/person\/fd81c4b213566f3add82d0f214928dfa","name":"l.sempere","image":{"@type":"ImageObject","@id":"https:\/\/internacional.umh.es\/en\/#personlogo","inLanguage":"ca","url":"https:\/\/secure.gravatar.com\/avatar\/1f9861c855fb90ab758094a71cf6e565?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f9861c855fb90ab758094a71cf6e565?s=96&d=mm&r=g","caption":"l.sempere"},"url":"https:\/\/internacional.umh.es\/ca\/author\/l-sempere\/"}]}},"_links":{"self":[{"href":"https:\/\/internacional.umh.es\/ca\/wp-json\/wp\/v2\/posts\/35089"}],"collection":[{"href":"https:\/\/internacional.umh.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internacional.umh.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internacional.umh.es\/ca\/wp-json\/wp\/v2\/users\/6508"}],"replies":[{"embeddable":true,"href":"https:\/\/internacional.umh.es\/ca\/wp-json\/wp\/v2\/comments?post=35089"}],"version-history":[{"count":0,"href":"https:\/\/internacional.umh.es\/ca\/wp-json\/wp\/v2\/posts\/35089\/revisions"}],"wp:attachment":[{"href":"https:\/\/internacional.umh.es\/ca\/wp-json\/wp\/v2\/media?parent=35089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internacional.umh.es\/ca\/wp-json\/wp\/v2\/categories?post=35089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internacional.umh.es\/ca\/wp-json\/wp\/v2\/tags?post=35089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}